{"id":5535,"date":"2026-03-24T15:17:34","date_gmt":"2026-03-24T14:17:34","guid":{"rendered":"https:\/\/newpropaccdev.wpenginepowered.com\/?p=5535"},"modified":"2026-04-06T13:07:35","modified_gmt":"2026-04-06T11:07:35","slug":"how-to-start-a-prop-firm-with-minimal-capital","status":"publish","type":"post","link":"https:\/\/propaccount.com\/es\/resources\/blog\/how-to-start-a-prop-firm-with-minimal-capital\/","title":{"rendered":"\u00bfC\u00f3mo Iniciar una Firma de Prop Trading con Capital M\u00ednimo?"},"content":{"rendered":"<h2><span style=\"font-weight: 400;\">\u00bfSe Puede Iniciar una Firma de Prop Trading con Poco Capital?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La idea de lanzar una firma de trading propietaria sol\u00eda venir con un alto costo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los operadores necesitaban un capital de trading considerable, relaciones de liquidez, sistemas de riesgo, plataformas de trading, procesamiento de pagos, paneles de control para traders y una configuraci\u00f3n operativa completa. Y construir todo eso requer\u00eda una financiaci\u00f3n significativa, experiencia t\u00e9cnica y meses de desarrollo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hoy, el panorama del trading es completamente diferente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los grandes avances en <\/span><a href=\"https:\/\/propaccount.com\/es\/blog\/the-best-prop-firm-technology-powering-proprietary-trading\/\"><span style=\"font-weight: 400;\">tecnolog\u00eda de prop trading<\/span><\/a><span style=\"font-weight: 400;\"> han reducido dr\u00e1sticamente las barreras de entrada. Con los proveedores de infraestructura modernos, los emprendedores pueden lanzar su firma sin tener que reunir grandes cantidades de capital para la firma de prop trading o construir sistemas complejos desde cero.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As\u00ed que la verdadera pregunta ya no es si puedes iniciar una firma de prop trading con poco capital. La pregunta es c\u00f3mo funciona realmente el modelo.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Comprendiendo el Modelo Moderno de Firma de Prop Trading<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Para entender <\/span><a href=\"https:\/\/propaccount.com\/es\/blog\/how-to-start-a-prop-firm-60-day-survival-framework\/\"><span style=\"font-weight: 400;\">c\u00f3mo iniciar una firma de prop trading<\/span><\/a><span style=\"font-weight: 400;\"> con poco capital, ayuda observar c\u00f3mo operan hoy las firmas de prop trading.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En lugar de financiar a los traders con grandes fondos de capital de inmediato, muchas firmas utilizan un modelo de desaf\u00edo o evaluaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esta estructura:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los traders pagan una tarifa para participar en un desaf\u00edo de trading<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">El desaf\u00edo pone a prueba su disciplina, estrategia y gesti\u00f3n de riesgos<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los traders que aprueban reciben acceso a una cuenta fondeada<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Las ganancias se comparten entre el trader y la firma<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Este enfoque reduce dr\u00e1sticamente la cantidad de capital necesaria para lanzar una firma de trading propietaria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La firma no necesita financiar a miles de traders con capital real desde el primer d\u00eda. En cambio, los traders demuestran su habilidad a trav\u00e9s de evaluaciones estructuradas antes de acceder a cuentas m\u00e1s grandes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para los operadores, este modelo crea un negocio que se centra en la tecnolog\u00eda, la gesti\u00f3n de riesgos y la infraestructura del trader, en lugar de la pura implementaci\u00f3n de capital.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfPor qu\u00e9 iniciar una firma de trading propietaria sol\u00eda ser caro?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Hace solo unos a\u00f1os, lanzar una firma de trading propietaria requer\u00eda construir casi todo desde cero.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los emprendedores necesitaban ensamblar m\u00faltiples sistemas complejos, incluyendo:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Plataformas de trading y sistemas de ejecuci\u00f3n<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Infraestructura de gesti\u00f3n de riesgos<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Paneles de control y an\u00e1lisis para traders<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Procesos de incorporaci\u00f3n y verificaci\u00f3n<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sistemas de pago y desembolso<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Herramientas de CRM y gesti\u00f3n de traders<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Cada pieza de tecnolog\u00eda a menudo proven\u00eda de un proveedor diferente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Integrar esos sistemas era costoso, requer\u00eda mucho tiempo y era t\u00e9cnicamente desafiante. Incluso las empresas peque\u00f1as pod\u00edan gastar cientos de miles de d\u00f3lares antes de su lanzamiento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En muchos casos, los operadores no estaban construyendo una firma de fondeo. Estaban construyendo una empresa de tecnolog\u00eda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para la mayor\u00eda de los emprendedores, esa barrera hac\u00eda que la idea de lanzar una firma de fondeo fuera poco realista.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfPor qu\u00e9 la tecnolog\u00eda lo cambi\u00f3 todo?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La industria del prop trading ha madurado r\u00e1pidamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En lugar de unir m\u00faltiples proveedores, los operadores ahora pueden usar tecnolog\u00eda de prop trading integrada dise\u00f1ada espec\u00edficamente para lanzar y escalar firmas de fondeo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estas plataformas combinan componentes esenciales en un solo sistema:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Integraciones de plataformas de trading<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Gesti\u00f3n de riesgo automatizada<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Paneles de control y an\u00e1lisis para traders<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sistemas de evaluaci\u00f3n y desaf\u00edo<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Flujos de trabajo de pago e incorporaci\u00f3n<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Paneles de administraci\u00f3n para operadores de firmas<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Al centralizar estas herramientas, las plataformas modernas de prop tech eliminan gran parte de la complejidad que antes requer\u00eda grandes presupuestos de desarrollo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En lugar de pasar meses construyendo infraestructura, los operadores pueden lanzar con sistemas que ya est\u00e1n dise\u00f1ados para las operaciones de una firma de fondeo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este cambio es la raz\u00f3n principal por la que iniciar una firma de fondeo con capital m\u00ednimo se ha vuelto posible.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">De d\u00f3nde viene la idea de \u201cSin Dinero\u201d<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Cuando la gente pregunta c\u00f3mo iniciar una firma de trading propietaria sin dinero, generalmente se refieren a las barreras financieras reducidas creadas por la infraestructura moderna.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los operadores ya no necesitan comprometer grandes cantidades de capital de trading o contratar equipos t\u00e9cnicos completos antes de lanzar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cambio, el enfoque se desplaza a tres \u00e1reas:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Marca y posicionamiento: <\/b><span style=\"font-weight: 400;\">Las firmas exitosas construyen una fuerte identidad de marca y una mensajer\u00eda clara en torno a sus programas de trading.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Adquisici\u00f3n de traders: <\/b><span style=\"font-weight: 400;\">El marketing y las asociaciones impulsan el crecimiento de la comunidad de traders.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Consistencia operativa: <\/b><span style=\"font-weight: 400;\">Reglas claras, plataformas estables y pagos fiables ayudan a las firmas a construir confianza a largo plazo.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Los proveedores de tecnolog\u00eda manejan gran parte de la infraestructura compleja entre bastidores, permitiendo que el enfoque est\u00e9 en el crecimiento del negocio en s\u00ed.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Lo que a\u00fan necesitas para lanzar<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Si bien los requisitos de capital han disminuido significativamente, lanzar una firma de trading propietaria a\u00fan requiere una planificaci\u00f3n cuidadosa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Incluso con infraestructura moderna, los operadores deben pensar en varios elementos clave.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Un modelo de negocio claro: <\/b><span style=\"font-weight: 400;\">La estructura de evaluaci\u00f3n, los tama\u00f1os de cuenta y los repartos de ganancias deben definirse claramente.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Experiencia del trader: <\/b><span style=\"font-weight: 400;\">Las plataformas deben ser estables, r\u00e1pidas y f\u00e1ciles de usar.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Gesti\u00f3n de riesgos: <\/b><span style=\"font-weight: 400;\">Los l\u00edmites de p\u00e9rdidas, la aplicaci\u00f3n de reglas y los sistemas de monitoreo deben operar en tiempo real.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Estrategia de marketing: <\/b><span style=\"font-weight: 400;\">Los programas de afiliados, la promoci\u00f3n en redes sociales y las asociaciones suelen ser los principales impulsores del crecimiento.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Atenci\u00f3n al cliente: <\/b><span style=\"font-weight: 400;\">Los traders esperan respuestas r\u00e1pidas, reglas claras y comunicaci\u00f3n fiable.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">La diferencia hoy es que los operadores ya no necesitan construir estos sistemas ellos mismos.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">La importancia de una infraestructura s\u00f3lida<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Detr\u00e1s de cada firma de prop trading exitosa hay una s\u00f3lida base operativa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los entornos de trading deben soportar un gran n\u00famero de traders simult\u00e1neamente, manteniendo un rendimiento constante y un monitoreo preciso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si los sistemas fallan, los traders lo notan inmediatamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los retrasos en la ejecuci\u00f3n, la inestabilidad de la plataforma o los an\u00e1lisis inexactos da\u00f1an r\u00e1pidamente la confianza.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por eso muchos conf\u00edan en proveedores de tecnolog\u00eda especializada para prop trading que ya dan soporte a m\u00faltiples firmas y grandes comunidades de traders.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una infraestructura estable reduce la fricci\u00f3n operativa y permite a las firmas escalar sin tener que reconstruir sistemas constantemente.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Escalar una firma de prop trading con \u00e9xito<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Lanzar una firma de fondeo es solo el primer paso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El verdadero desaf\u00edo surge cuando la comunidad de traders comienza a crecer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A medida que m\u00e1s traders se unen, varias demandas operativas aumentan:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mayor volumen de operaciones<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">M\u00e1s cuentas que monitorear<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ciclos de pago m\u00e1s grandes<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mayor n\u00famero de solicitudes de soporte al cliente<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Sin sistemas tecnol\u00f3gicos s\u00f3lidos, el crecimiento r\u00e1pidamente crea cuellos de botella operativos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las firmas de fondeo modernas escalan con \u00e9xito cuando su infraestructura puede manejar a miles de traders manteniendo la estabilidad y una clara aplicaci\u00f3n de las reglas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqu\u00ed es donde la tecnolog\u00eda integrada para firmas de fondeo se vuelve esencial.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfPuede una Firma de Fondeo Realmente Empezar con Poco Capital?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En la pr\u00e1ctica, lanzar una firma de fondeo rara vez significa no gastar absolutamente nada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, ahora es posible iniciar una firma sin comprometer un gran capital de trading o liquidez.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En lugar de financiar cuentas directamente, los emprendedores pueden lanzar utilizando plataformas tecnol\u00f3gicas que proporcionan la infraestructura operativa necesaria para gestionar una firma de fondeo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esto reduce dr\u00e1sticamente la barrera financiera de entrada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En lugar de construir sistemas desde cero o recaudar capital significativo, los emprendedores pueden centrarse en desarrollar la marca, atraer traders y hacer crecer la comunidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para muchos, el desaf\u00edo ya no es el acceso al capital. El verdadero desaf\u00edo es construir un entorno de trading estable y confiable en el que los traders quieran participar.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">El futuro de los lanzamientos de firmas de prop trading de bajo costo<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Lanzar una firma de prop trading es m\u00e1s f\u00e1cil que nunca. Construir una en la que los traders realmente conf\u00eden es el verdadero desaf\u00edo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada mes se lanzan nuevas firmas a medida que la tecnolog\u00eda facilita m\u00e1s que nunca la entrada al mercado. Pero si bien la barrera de entrada ha disminuido, las expectativas de los traders han aumentado con la misma rapidez.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hoy en d\u00eda, los traders buscan plataformas estables, reglas claras y pagos en los que puedan confiar. Las firmas que tienen \u00e9xito son aquellas que construyen un entorno de trading donde todo funciona sin problemas entre bastidores.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lanzar una firma de prop trading puede que ya no requiera un capital masivo, pero construir confianza a\u00fan requiere sistemas s\u00f3lidos.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/propaccount.com\/es\/\"><span style=\"font-weight: 400;\">Cuenta Propia<\/span><\/a><span style=\"font-weight: 400;\"> es la respuesta. Proporcionamos la infraestructura que permite a los operadores lanzar y escalar firmas de prop trading sin tener que ensamblar complejas pilas de tecnolog\u00eda ellos mismos. Y con la base establecida, puedes concentrarte en lo que realmente impulsa el crecimiento: construir una marca s\u00f3lida, atraer traders cualificados y desarrollar un negocio de prop trading que perdure. Desde el primer d\u00eda.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Preguntas frecuentes: Iniciar una firma de prop trading sin dinero<\/span><\/h2>\n<p><b>P: \u00bfRealmente se puede iniciar una firma de prop trading sin dinero?<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Muchos operadores lanzan una firma de prop trading con un capital m\u00ednimo utilizando la infraestructura de prop trading existente en lugar de construir tecnolog\u00eda desde cero.<\/span><\/p>\n<p><b>P: \u00bfCu\u00e1l es el mayor costo al iniciar una firma de prop trading?<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">La tecnolog\u00eda suele llevarse la mayor parte del gasto, incluyendo plataformas de trading, infraestructura y los sistemas necesarios para operar la firma.<\/span><\/p>\n<p><b>P: \u00bfNecesitan capital de trading las firmas de prop trading?<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">No siempre. Muchas firmas utilizan modelos de evaluaci\u00f3n donde los traders demuestran su rendimiento antes de recibir cuentas fondeadas.<\/span><\/p>\n<p><b>P: \u00bfQu\u00e9 tecnolog\u00eda necesita una firma de prop trading?<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">La mayor\u00eda de las firmas tienen una lista imprescindible que incluye: plataformas de trading, herramientas de gesti\u00f3n de riesgos, paneles de control para traders, sistemas de pago y an\u00e1lisis de rendimiento.<\/span><\/p>\n<p><b>P: \u00bfC\u00f3mo ganan dinero las firmas de trading propietarias?<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">La mayor\u00eda de las firmas de trading propietarias generan ingresos a trav\u00e9s de tarifas de evaluaci\u00f3n y tomando un porcentaje de las ganancias de los traders una vez que las cuentas est\u00e1n financiadas.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Aprende c\u00f3mo la tecnolog\u00eda moderna de las firmas de trading propietarias permite a los operadores lanzar y escalar firmas de trading propietarias sin un gran capital inicial.<\/p>","protected":false},"author":1,"featured_media":5636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[116],"tags":[],"class_list":["post-5535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/posts\/5535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/comments?post=5535"}],"version-history":[{"count":0,"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/posts\/5535\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/media\/5636"}],"wp:attachment":[{"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/media?parent=5535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/categories?post=5535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/propaccount.com\/es\/wp-json\/wp\/v2\/tags?post=5535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}